{"id":52266,"date":"2019-11-15T13:09:22","date_gmt":"2019-11-15T12:09:22","guid":{"rendered":""},"modified":"2019-11-22T12:18:36","modified_gmt":"2019-11-22T11:18:36","slug":"miami-iced-tea","status":"publish","type":"cocktail","link":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/","title":{"rendered":"Miami Iced Tea by MIXOLOGY Academy"},"content":{"rendered":"<p>Variazione del <strong>cocktail<\/strong>\u00a0<strong>Long Island Iced Tea<\/strong>, con il <a href=\"https:\/\/www.mixolopedia.com\/it\/alcoholic\/bols-blue-curacao\/\">Blue Caracao<\/a> al posto del <a href=\"https:\/\/www.mixolopedia.com\/it\/alcoholic-category\/triple-sec-it\/\">Triple Sec<\/a> e la Lemonsoda al posto della Cola. Quella che trovi qui \u00e8 una variante della ricetta rivista nelle dosi da MIXOLOGY Academy.<\/p>\n","protected":false},"author":11,"featured_media":54165,"template":"","cocktail-category":[806,800],"class_list":["post-52266","cocktail","type-cocktail","status-publish","has-post-thumbnail","hentry","cocktail-category-ice-tea-it","cocktail-category-long-drink-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Miami Iced Tea ricetta by MIXOLOGY Academy | MixolopediA<\/title>\n<meta name=\"description\" content=\"Variazione del cocktail\u00a0Long Island Iced Tea, con Blue Caracao e Lemonsoda. Scopri questa variante della ricetta di MIXOLOGY Academy!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miami Iced Tea ricetta by MIXOLOGY Academy | MixolopediA\" \/>\n<meta property=\"og:description\" content=\"Variazione del cocktail\u00a0Long Island Iced Tea, con Blue Caracao e Lemonsoda. Scopri questa variante della ricetta di MIXOLOGY Academy!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/\" \/>\n<meta property=\"og:site_name\" content=\"Cocktails Spirits Liquors\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-22T11:18:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"310\" \/>\n\t<meta property=\"og:image:height\" content=\"310\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/\",\"url\":\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/\",\"name\":\"Miami Iced Tea ricetta by MIXOLOGY Academy | MixolopediA\",\"isPartOf\":{\"@id\":\"http:\/\/mixolopedia.test\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg\",\"datePublished\":\"2019-11-15T12:09:22+00:00\",\"dateModified\":\"2019-11-22T11:18:36+00:00\",\"description\":\"Variazione del cocktail\u00a0Long Island Iced Tea, con Blue Caracao e Lemonsoda. Scopri questa variante della ricetta di MIXOLOGY Academy!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#primaryimage\",\"url\":\"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg\",\"contentUrl\":\"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg\",\"width\":310,\"height\":310,\"caption\":\"miami iced tea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/mixolopedia.test\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cocktail\",\"item\":\"http:\/\/mixolopedia.test\/cocktail\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Miami Iced Tea by MIXOLOGY Academy\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/mixolopedia.test\/#website\",\"url\":\"http:\/\/mixolopedia.test\/\",\"name\":\"Cocktails Spirits Liquors\",\"description\":\"Un nuovo sito targato WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/mixolopedia.test\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miami Iced Tea ricetta by MIXOLOGY Academy | MixolopediA","description":"Variazione del cocktail\u00a0Long Island Iced Tea, con Blue Caracao e Lemonsoda. Scopri questa variante della ricetta di MIXOLOGY Academy!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/","og_locale":"it_IT","og_type":"article","og_title":"Miami Iced Tea ricetta by MIXOLOGY Academy | MixolopediA","og_description":"Variazione del cocktail\u00a0Long Island Iced Tea, con Blue Caracao e Lemonsoda. Scopri questa variante della ricetta di MIXOLOGY Academy!","og_url":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/","og_site_name":"Cocktails Spirits Liquors","article_modified_time":"2019-11-22T11:18:36+00:00","og_image":[{"width":310,"height":310,"url":"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/","url":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/","name":"Miami Iced Tea ricetta by MIXOLOGY Academy | MixolopediA","isPartOf":{"@id":"http:\/\/mixolopedia.test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#primaryimage"},"image":{"@id":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg","datePublished":"2019-11-15T12:09:22+00:00","dateModified":"2019-11-22T11:18:36+00:00","description":"Variazione del cocktail\u00a0Long Island Iced Tea, con Blue Caracao e Lemonsoda. Scopri questa variante della ricetta di MIXOLOGY Academy!","breadcrumb":{"@id":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#primaryimage","url":"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg","contentUrl":"https:\/\/www.mixolopedia.com\/wp-content\/uploads\/2019\/11\/miami-iced-tea-cocktail.jpg","width":310,"height":310,"caption":"miami iced tea"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mixolopedia.com\/it\/cocktail\/miami-iced-tea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/mixolopedia.test\/it\/"},{"@type":"ListItem","position":2,"name":"Cocktail","item":"http:\/\/mixolopedia.test\/cocktail\/"},{"@type":"ListItem","position":3,"name":"Miami Iced Tea by MIXOLOGY Academy"}]},{"@type":"WebSite","@id":"http:\/\/mixolopedia.test\/#website","url":"http:\/\/mixolopedia.test\/","name":"Cocktails Spirits Liquors","description":"Un nuovo sito targato WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/mixolopedia.test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.mixolopedia.com\/it\/wp-json\/wp\/v2\/cocktail\/52266"}],"collection":[{"href":"https:\/\/www.mixolopedia.com\/it\/wp-json\/wp\/v2\/cocktail"}],"about":[{"href":"https:\/\/www.mixolopedia.com\/it\/wp-json\/wp\/v2\/types\/cocktail"}],"author":[{"embeddable":true,"href":"https:\/\/www.mixolopedia.com\/it\/wp-json\/wp\/v2\/users\/11"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mixolopedia.com\/it\/wp-json\/wp\/v2\/media\/54165"}],"wp:attachment":[{"href":"https:\/\/www.mixolopedia.com\/it\/wp-json\/wp\/v2\/media?parent=52266"}],"wp:term":[{"taxonomy":"cocktail-category","embeddable":true,"href":"https:\/\/www.mixolopedia.com\/it\/wp-json\/wp\/v2\/cocktail-category?post=52266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}